{"id":75263,"date":"2023-11-14T12:01:11","date_gmt":"2023-11-14T15:01:11","guid":{"rendered":"https:\/\/cleitonpinheiro.com.br\/site\/?p=75263"},"modified":"2023-12-27T10:25:22","modified_gmt":"2023-12-27T13:25:22","slug":"saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo","status":"publish","type":"post","link":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/","title":{"rendered":"Saiba como o calor excessivo altera metabolismo do corpo"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" src=\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/11\/trbr5837-1-1024x613.webp\" alt=\"\" class=\"wp-image-75264\"\/><figcaption class=\"wp-element-caption\">Desidrata\u00e7\u00e3o e queimaduras solares s\u00e3o alguns dos riscos nesse per\u00edodo &#8211; Foto: T\u00e2nia R\u00eago\/Ag\u00eancia Brasil &#8211; Foto: T\u00e2nia R\u00eago\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">As mudan\u00e7as bruscas de temperatura verificadas nos \u00faltimos dias no pa\u00eds alteram muito o metabolismo do corpo humano. O calor excessivo pode levar \u00e0 desidrata\u00e7\u00e3o e provocar queimaduras solares, se a pessoa estiver sem prote\u00e7\u00e3o, alertou nesta segunda-feira (13) a m\u00e9dica Marcela Benez, coordenadora do Departamento de Cirurgia e Oncologia da Sociedade Brasileira de Dermatologia do Rio de Janeiro (SBD-RJ).<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1566311&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1566311&amp;o=node\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As queimaduras podem ocorrer em quem est\u00e1 exposto diretamente ao sol na face e onde a roupa n\u00e3o cobre. \u201c\u00c9 importante sempre fazer uso de filtro solar antes de sair de casa, usar roupas mais frescas e fazer reposi\u00e7\u00e3o de \u00e1gua e outros meios de hidrata\u00e7\u00e3o ao longo do dia\u201d, disse Marcela, em entrevista \u00e0&nbsp;<strong>Ag\u00eancia Brasil<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre o c\u00e2ncer de pele, a m\u00e9dica explicou que ele aparece com o ac\u00famulo de fotoexposi\u00e7\u00e3o ao longo da vida e devido a queimaduras solares. Segundo Marcela, a queimadura feita na inf\u00e2ncia vai gerando altera\u00e7\u00e3o no DNA da c\u00e9lula, e isso vai se acumulando ao longo da vida. &#8220;\u00c9 uma exposi\u00e7\u00e3o mais prolongada. N\u00e3o \u00e9 de imediato, mas v\u00e1rias exposi\u00e7\u00f5es podem ser fator de risco.\u201d Com a exposi\u00e7\u00e3o prolongada ao sol, o c\u00e2ncer de pele pode come\u00e7ar a surgir no adulto jovem e na pessoa idosa. \u201cTem pessoas com 30 e poucos anos e at\u00e9 com 20 e poucos anos com c\u00e2ncer de pele, resultado de grande exposi\u00e7\u00e3o ao sol desde crian\u00e7as. A queimadura solar que faz eritemas e bolhas na pele vai gerando isso no futuro, na idade mais adulta.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algumas doen\u00e7as podem ser agravadas pelas temperaturas elevadas, especialmente as fotossensibilizantes, como l\u00fapus e a dermatomiosite, que s\u00e3o autoimunes. \u201cS\u00e3o agravadas diretamente pelo sol e pelo calor\u201d. Tamb\u00e9m a dermatite at\u00f3pica (doen\u00e7a cr\u00f4nica e heredit\u00e1ria que causa inflama\u00e7\u00e3o da pele, levando ao aparecimento de les\u00f5es e coceira) pode ficar um pouco descontrolada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A dermatologista recomendou que as pessoas, diante dessas temperaturas elevadas, fa\u00e7am a fotoprote\u00e7\u00e3o, que inclui o uso de chap\u00e9us, barracas na praia e piscina, roupas com fator UV de prote\u00e7\u00e3o, al\u00e9m do filtro solar, que deve ser passado na pele ainda em casa, antes da exposi\u00e7\u00e3o ao sol, e reaplicado, em m\u00e9dia, duas ou tr\u00eas horas depois, que \u00e9 o tempo de dura\u00e7\u00e3o na pele. \u201cCom o suor, ou quando a pessoa se molha na piscina ou na praia, o protetor deve ser reaplicado.\u201d<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Botando para fora<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">A endocrinologista Ana Cristina Belsito, do Hospital S\u00e3o Vicente de Paulo e membro da Sociedade Brasileira de Endocrinologia e Metabologia, enfatizou que, nos casos de calor excessivo, \u00e9 preciso botar para fora o calor. &#8220;A sudorese aumenta nesse per\u00edodo, a pessoa come\u00e7a a suar mais, e o s\u00f3dio tende a cair. Os n\u00edveis tensionais [n\u00edveis de press\u00e3o arterial] tamb\u00e9m caem com isso\u201d, disse Ana Cristina \u00e0&nbsp;<strong>Ag\u00eancia Brasil<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Outra coisa importante \u00e9 a possibilidade de deteriora\u00e7\u00e3o dos alimentos. \u201cMuitas vezes, a conserva\u00e7\u00e3o dos alimentos n\u00e3o \u00e9 t\u00e3o bem-feita nos locais onde se fazem refei\u00e7\u00f5es, e isso aumenta o risco de infec\u00e7\u00f5es intestinais, como diarreia, que fazem com que as pessoas tenham outros problemas de desidrata\u00e7\u00e3o.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m disso, Ana Cristina reiterou a necessidade de tomar cuidado com as roupas. \u201cAs vestimentas t\u00eam de ser mais frescas, para eliminar calor, porque nosso organismo fica muito aquecido. E as comidas t\u00eam que ser leves, frescas. Importante a hidrata\u00e7\u00e3o e a prote\u00e7\u00e3o solar tamb\u00e9m, contra a radia\u00e7\u00e3o ultravioleta intensa e queimadura de pele.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A m\u00e9dica refor\u00e7ou que as pessoas devem se hidratar bem nesse per\u00edodo de calor excessivo e evitar se expor nos hor\u00e1rios de pico, desempenhando suas atividades em hor\u00e1rios de temperatura mais amena. &#8220;Os sinais que a falta de \u00e1gua no organismo pode gerar incluem prostra\u00e7\u00e3o, desidrata\u00e7\u00e3o, dor de cabe\u00e7a [cefaleia], boca seca, desorienta\u00e7\u00e3o. \u201cS\u00e3o sinais que alertam que o organismo n\u00e3o est\u00e1 bem.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os hipertensas, que costumam usar diur\u00e9ticos com frequ\u00eancia, devem ficar atentos. O excesso de medica\u00e7\u00e3o, quando a pessoa \u00e9 submetida a uma carga maior de temperatura, faz com que ela perca \u00e1gua. Com essa perda, pode haver um desequil\u00edbrio hidroeletrol\u00edtico e, junto com a sudorese, isso pode fazer com que a press\u00e3o caia muito, mais do que o normal. Ana Cristina alertou que esse quadro pode levar \u00e0 desorienta\u00e7\u00e3o, desidrata\u00e7\u00e3o e prostra\u00e7\u00e3o, al\u00e9m de gerar altera\u00e7\u00f5es renais devido ao menor aporte de \u00e1gua. A desorienta\u00e7\u00e3o \u00e9 o sintoma mais frequente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Caso a pessoa tenha esses sintomas, a recomenda\u00e7\u00e3o \u00e9 procurar um servi\u00e7o de emerg\u00eancia, pronto atendimento, para fazer os exames necess\u00e1rios como s\u00f3dio, pot\u00e1ssio, ureia, creatinina, hemograma. Se necess\u00e1rio for, deve ainda medir a press\u00e3o. Feitos os exames de urg\u00eancia, o indiv\u00edduo \u00e9 encaminhado ao m\u00e9dico especializado na \u00e1rea do problema que estiver apresentando.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Doen\u00e7as cardiovasculares<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">O coordenador assistencial do Instituto Nacional de Cardiologia (INC), Alexandre Rouge, ressaltou que, quando se fala de aumento da temperatura, \u00e9 preciso entender duas coisas: uma \u00e9 o aquecimento global, que, no longo prazo, pode estar relacionado ao&nbsp;<a href=\"https:\/\/agenciabrasil.ebc.com.br\/radioagencia-nacional\/meio-ambiente\/audio\/2021-07\/aquecimento-global-pode-gerar-aumento-de-mortes-por-estresse-termico\" target=\"_blank\" rel=\"noreferrer noopener\">aumento progressivo das doen\u00e7as cardiovasculares<\/a>. J\u00e1 h\u00e1, inclusive, um estudo da Funda\u00e7\u00e3o Oswaldo Cruz (Fiocruz) mostrando isso, disse Rouge.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos meses mais quentes do ano, o aumento da temperatura, somado \u00e0 redu\u00e7\u00e3o da umidade do ar, tamb\u00e9m aumenta os eventos cardiovasculares. \u201cPara tentar compensar o calor, a gente dilata os vasos e, fazendo isso, tem quedas de press\u00e3o e aumento de frequ\u00eancia card\u00edaca, o que favorece o consumo do cora\u00e7\u00e3o. Aumenta-se o consumo do cora\u00e7\u00e3o por oxig\u00eanio, e isso pode levar \u00e0 instabilidade de uma doen\u00e7a que esteja ali quietinha\u201d, destacou.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rouge lembrou que a pessoa sua mais e, a\u00ed, acaba se desidratando e perdendo os eletr\u00f3litos do sangue (s\u00f3dio, pot\u00e1ssio), tem menos volume de sangue no organismo, o que tamb\u00e9m facilita a queda de press\u00e3o e o aparecimento de eventos cardiovasculares. \u201cO suor e a queda desses sais favorecem o aparecimento de arritmias, principalmente nos idosos. Ent\u00e3o, o aumento da temperatura favorece tanto eventos isqu\u00eamicos do cora\u00e7\u00e3o, que s\u00e3o as anginas e infartos, como eventos de arritmia.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hidrata\u00e7\u00e3o o tempo todo \u00e9 o principal cuidado para evitar problemas card\u00edacos nos per\u00edodos de altas temperaturas. Se poss\u00edvel, a pessoa deve andar com uma garrafinha de \u00e1gua, para n\u00e3o se esquecer da hidrata\u00e7\u00e3o e evitar atividades f\u00edsicas nos momentos de maior calor. \u201cN\u00e3o \u00e9 para parar a atividade f\u00edsica, porque isso tamb\u00e9m seria ruim, mas n\u00e3o fazer nos hor\u00e1rios de pico de calor.\u201d Quando estiver em \u00e1reas expostas ao sol, a pessoa deve buscar sempre um local mais fresco, ao longo do dia, se poss\u00edvel, ambientes refrigerados, como dar uma passada em uma galeria ou&nbsp;<em>shopping center<\/em>&nbsp;onde possa passar algumas horas em ambiente mais refrigerado, fugindo da onda de calor, acrescentou o cardiologista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo Rouge, do ponto de vista do cora\u00e7\u00e3o, a pessoa precisa estar sempre alerta \u2013 como deve ser durante todo o ano \u2013 para sintomas como dor no peito, desmaios, palpita\u00e7\u00f5es. N\u00e3o h\u00e1, por\u00e9m, nenhuma recomenda\u00e7\u00e3o de exame extra a ser feito. \u201cS\u00f3 estar atento aos sintomas.\u201d E procurar o m\u00e9dico, se os sintomas persistirem, a orienta\u00e7\u00e3o \u00e9 procurar o m\u00e9dico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Texto: Alana Gandra \u2013 Ag\u00eancia Brasil\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As mudan\u00e7as bruscas de temperatura verificadas nos \u00faltimos dias no pa\u00eds alteram muito o metabolismo do corpo humano. O calor excessivo pode levar \u00e0 desidrata\u00e7\u00e3o e provocar queimaduras solares, se a pessoa estiver sem prote\u00e7\u00e3o, alertou nesta segunda-feira (13) a m\u00e9dica Marcela Benez, coordenadora do Departamento de Cirurgia e Oncologia da Sociedade Brasileira de Dermatologia [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19,21],"tags":[],"class_list":["post-75263","post","type-post","status-publish","format-standard","hentry","category-brasil-mundo","category-todas-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Saiba como o calor excessivo altera metabolismo do corpo - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Saiba como o calor excessivo altera metabolismo do corpo - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\" \/>\n<meta property=\"og:description\" content=\"As mudan\u00e7as bruscas de temperatura verificadas nos \u00faltimos dias no pa\u00eds alteram muito o metabolismo do corpo humano. O calor excessivo pode levar \u00e0 desidrata\u00e7\u00e3o e provocar queimaduras solares, se a pessoa estiver sem prote\u00e7\u00e3o, alertou nesta segunda-feira (13) a m\u00e9dica Marcela Benez, coordenadora do Departamento de Cirurgia e Oncologia da Sociedade Brasileira de Dermatologia [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/\" \/>\n<meta property=\"og:site_name\" content=\"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcpnoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-14T15:01:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-27T13:25:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/11\/trbr5837-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"700\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o CP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o CP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o CP\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db\"},\"headline\":\"Saiba como o calor excessivo altera metabolismo do corpo\",\"datePublished\":\"2023-11-14T15:01:11+00:00\",\"dateModified\":\"2023-12-27T13:25:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/\"},\"wordCount\":1317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/11\/trbr5837-1-1024x613.webp\",\"articleSection\":[\"BRASIL \/ MUNDO\",\"TODAS NOTICIAS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/\",\"name\":\"Saiba como o calor excessivo altera metabolismo do corpo - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\",\"isPartOf\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/11\/trbr5837-1-1024x613.webp\",\"datePublished\":\"2023-11-14T15:01:11+00:00\",\"dateModified\":\"2023-12-27T13:25:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/cleitonpinheiro.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Saiba como o calor excessivo altera metabolismo do corpo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#website\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/\",\"name\":\"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\",\"description\":\"FALANDO A VERDADE\",\"publisher\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cleitonpinheiro.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\",\"name\":\"CPNOT\u00cdCIAS\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png\",\"contentUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png\",\"width\":500,\"height\":500,\"caption\":\"CPNOT\u00cdCIAS\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/portalcpnoticias\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db\",\"name\":\"Reda\u00e7\u00e3o CP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g\",\"caption\":\"Reda\u00e7\u00e3o CP\"},\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Saiba como o calor excessivo altera metabolismo do corpo - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/","og_locale":"pt_BR","og_type":"article","og_title":"Saiba como o calor excessivo altera metabolismo do corpo - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","og_description":"As mudan\u00e7as bruscas de temperatura verificadas nos \u00faltimos dias no pa\u00eds alteram muito o metabolismo do corpo humano. O calor excessivo pode levar \u00e0 desidrata\u00e7\u00e3o e provocar queimaduras solares, se a pessoa estiver sem prote\u00e7\u00e3o, alertou nesta segunda-feira (13) a m\u00e9dica Marcela Benez, coordenadora do Departamento de Cirurgia e Oncologia da Sociedade Brasileira de Dermatologia [&hellip;]","og_url":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/","og_site_name":"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","article_publisher":"https:\/\/www.facebook.com\/portalcpnoticias\/","article_published_time":"2023-11-14T15:01:11+00:00","article_modified_time":"2023-12-27T13:25:22+00:00","og_image":[{"width":1170,"height":700,"url":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/11\/trbr5837-1.webp","type":"image\/webp"}],"author":"Reda\u00e7\u00e3o CP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o CP","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#article","isPartOf":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/"},"author":{"name":"Reda\u00e7\u00e3o CP","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db"},"headline":"Saiba como o calor excessivo altera metabolismo do corpo","datePublished":"2023-11-14T15:01:11+00:00","dateModified":"2023-12-27T13:25:22+00:00","mainEntityOfPage":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/"},"wordCount":1317,"commentCount":0,"publisher":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#primaryimage"},"thumbnailUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/11\/trbr5837-1-1024x613.webp","articleSection":["BRASIL \/ MUNDO","TODAS NOTICIAS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/","url":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/","name":"Saiba como o calor excessivo altera metabolismo do corpo - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","isPartOf":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#primaryimage"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#primaryimage"},"thumbnailUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/11\/trbr5837-1-1024x613.webp","datePublished":"2023-11-14T15:01:11+00:00","dateModified":"2023-12-27T13:25:22+00:00","breadcrumb":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/cleitonpinheiro.com.br\/site\/saiba-como-o-calor-excessivo-altera-metabolismo-do-corpo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cleitonpinheiro.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Saiba como o calor excessivo altera metabolismo do corpo"}]},{"@type":"WebSite","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#website","url":"https:\/\/cleitonpinheiro.com.br\/site\/","name":"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","description":"FALANDO A VERDADE","publisher":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cleitonpinheiro.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization","name":"CPNOT\u00cdCIAS","url":"https:\/\/cleitonpinheiro.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png","contentUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png","width":500,"height":500,"caption":"CPNOT\u00cdCIAS"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcpnoticias\/"]},{"@type":"Person","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db","name":"Reda\u00e7\u00e3o CP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g","caption":"Reda\u00e7\u00e3o CP"},"url":"https:\/\/cleitonpinheiro.com.br\/site\/author\/redacao\/"}]}},"views":187,"_links":{"self":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/75263","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/comments?post=75263"}],"version-history":[{"count":1,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/75263\/revisions"}],"predecessor-version":[{"id":75265,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/75263\/revisions\/75265"}],"wp:attachment":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/media?parent=75263"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/categories?post=75263"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/tags?post=75263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}