{"id":75760,"date":"2023-12-05T15:08:02","date_gmt":"2023-12-05T18:08:02","guid":{"rendered":"https:\/\/cleitonpinheiro.com.br\/site\/?p=75760"},"modified":"2023-12-05T15:08:06","modified_gmt":"2023-12-05T18:08:06","slug":"procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas","status":"publish","type":"post","link":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/","title":{"rendered":"Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/12\/c877110731fa45e1b98314cb52a702b1.jpg\" alt=\"\" class=\"wp-image-75761\"\/><figcaption class=\"wp-element-caption\">Pesquisa foi realizada nas institui\u00e7\u00f5es de ensino que promovem educa\u00e7\u00e3o de n\u00edvel fundamental e m\u00e9dio<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Com o in\u00edcio do ano se aproximando, as escolas particulares j\u00e1 est\u00e3o fazendo a renova\u00e7\u00e3o das matr\u00edculas para o pr\u00f3ximo ano. O Procon Municipal de Palmas realizou uma pesquisa comparativa de pre\u00e7os das mensalidades escolares nas diversas institui\u00e7\u00f5es da Capital.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O levantamento foi realizado entre os dias 24 a 28 de novembro em 20 institui\u00e7\u00f5es de ensino que promovem educa\u00e7\u00e3o de n\u00edvel fundamental e m\u00e9dio. A pesquisa completa, que pode ser conferida&nbsp;<a href=\"https:\/\/agenciapalmas.com\/multimidiaSGN\/Anexo\/05.12.2023\/9c92509e3b5a4b868ce078b2435e3711.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">aqui<\/a>, apontou que do 6\u00b0 ao 9\u00b0 ano do n\u00edvel fundamental os valores das mensalidades variam entre R$ 412,00 a R$ 2.554,00. J\u00e1 os alunos que v\u00e3o cursar do 1\u00b0 ao 3\u00b0 ano do n\u00edvel m\u00e9dio os valores est\u00e3o fixados de R$ 528,00 a R$ 2.554,00.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o superintendente do Procon Municipal de Palmas, Rafael Dias, a Lei N\u00ba 9.870 de 23 de novembro de 1999, traz algumas orienta\u00e7\u00f5es que devem ser observadas e seguidas, sobre cobran\u00e7a de matr\u00edcula e de rematr\u00edcula que deve ser definida anualmente ou semestralmente &#8211; dependendo do regime adotado pela institui\u00e7\u00e3o. Ele lembrou que a normatiza\u00e7\u00e3o preconiza tamb\u00e9m sobre a desist\u00eancia da matr\u00edcula, que diz que o aluno ou respons\u00e1vel t\u00eam direito \u00e0 devolu\u00e7\u00e3o integral do valor pago pela matr\u00edcula, quando desistir do curso antes do in\u00edcio das aulas, pois considera que a escola pode preencher a vaga com outro aluno.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre o valor da mensalidade a mesma tem que ter validade de 12 meses a constar da assinatura do contrato. Antes desse prazo, qualquer reajuste \u00e9 proibido, como \u00e9 nula qualquer cl\u00e1usula contratual que indique revis\u00e3o ou reajuste antes de um ano.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Veja a seguir algumas orienta\u00e7\u00f5es espec\u00edficas do Procon Municipal sobre o processo que deve ser seguido pelos pais ou respons\u00e1veis legal ao realizarem matr\u00edcula ou rematr\u00edcula nas institui\u00e7\u00f5es de ensino particular.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Contato Direto:<\/strong>&nbsp;Entre em contato com a escola por telefone ou e-mail. A secretaria da escola, geralmente, fornece informa\u00e7\u00f5es detalhadas sobre o processo de matr\u00edcula, documentos necess\u00e1rios e valores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Site da Escola:<\/strong>&nbsp;Verifique o site oficial da escola, pois muitas institui\u00e7\u00f5es disponibilizam informa\u00e7\u00f5es sobre matr\u00edcula, documentos exigidos e taxas on-line.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Visita Presencial:<\/strong>&nbsp;Se poss\u00edvel, visite a escola pessoalmente. Algumas escolas oferecem&nbsp;<em>tours<\/em>&nbsp;para fam\u00edlias interessadas e isso pode ser uma oportunidade para esclarecer d\u00favidas sobre a matr\u00edcula.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Prazos e Documenta\u00e7\u00e3o:<\/strong>&nbsp;Certifique-se de entender os prazos para a matr\u00edcula e quais documentos s\u00e3o necess\u00e1rios. Geralmente, \u00e9 necess\u00e1rio apresentar documentos como certid\u00e3o de nascimento, comprovante de resid\u00eancia e hist\u00f3rico escolar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lembrando que essas s\u00e3o algumas orienta\u00e7\u00f5es gerais e que podem variar de acordo com a escola espec\u00edfica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Texto: Prefeitura de Palmas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o in\u00edcio do ano se aproximando, as escolas particulares j\u00e1 est\u00e3o fazendo a renova\u00e7\u00e3o das matr\u00edculas para o pr\u00f3ximo ano. O Procon Municipal de Palmas realizou uma pesquisa comparativa de pre\u00e7os das mensalidades escolares nas diversas institui\u00e7\u00f5es da Capital. O levantamento foi realizado entre os dias 24 a 28 de novembro em 20 institui\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[22,898,21],"tags":[],"class_list":["post-75760","post","type-post","status-publish","format-standard","hentry","category-cidades","category-manchete-segundaria","category-todas-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\" \/>\n<meta property=\"og:description\" content=\"Com o in\u00edcio do ano se aproximando, as escolas particulares j\u00e1 est\u00e3o fazendo a renova\u00e7\u00e3o das matr\u00edculas para o pr\u00f3ximo ano. O Procon Municipal de Palmas realizou uma pesquisa comparativa de pre\u00e7os das mensalidades escolares nas diversas institui\u00e7\u00f5es da Capital. O levantamento foi realizado entre os dias 24 a 28 de novembro em 20 institui\u00e7\u00f5es [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/\" \/>\n<meta property=\"og:site_name\" content=\"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcpnoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-05T18:08:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-05T18:08:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/12\/c877110731fa45e1b98314cb52a702b1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"533\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o CP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o CP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o CP\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db\"},\"headline\":\"Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas\",\"datePublished\":\"2023-12-05T18:08:02+00:00\",\"dateModified\":\"2023-12-05T18:08:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/\"},\"wordCount\":500,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/12\/c877110731fa45e1b98314cb52a702b1.jpg\",\"articleSection\":[\"CIDADES\",\"MANCHETE SEGUND\u00c1RIA\",\"TODAS NOTICIAS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/\",\"name\":\"Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\",\"isPartOf\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/12\/c877110731fa45e1b98314cb52a702b1.jpg\",\"datePublished\":\"2023-12-05T18:08:02+00:00\",\"dateModified\":\"2023-12-05T18:08:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/cleitonpinheiro.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#website\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/\",\"name\":\"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\",\"description\":\"FALANDO A VERDADE\",\"publisher\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cleitonpinheiro.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\",\"name\":\"CPNOT\u00cdCIAS\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png\",\"contentUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png\",\"width\":500,\"height\":500,\"caption\":\"CPNOT\u00cdCIAS\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/portalcpnoticias\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db\",\"name\":\"Reda\u00e7\u00e3o CP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g\",\"caption\":\"Reda\u00e7\u00e3o CP\"},\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/","og_locale":"pt_BR","og_type":"article","og_title":"Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","og_description":"Com o in\u00edcio do ano se aproximando, as escolas particulares j\u00e1 est\u00e3o fazendo a renova\u00e7\u00e3o das matr\u00edculas para o pr\u00f3ximo ano. O Procon Municipal de Palmas realizou uma pesquisa comparativa de pre\u00e7os das mensalidades escolares nas diversas institui\u00e7\u00f5es da Capital. O levantamento foi realizado entre os dias 24 a 28 de novembro em 20 institui\u00e7\u00f5es [&hellip;]","og_url":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/","og_site_name":"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","article_publisher":"https:\/\/www.facebook.com\/portalcpnoticias\/","article_published_time":"2023-12-05T18:08:02+00:00","article_modified_time":"2023-12-05T18:08:06+00:00","og_image":[{"width":800,"height":533,"url":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/12\/c877110731fa45e1b98314cb52a702b1.jpg","type":"image\/jpeg"}],"author":"Reda\u00e7\u00e3o CP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o CP","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#article","isPartOf":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/"},"author":{"name":"Reda\u00e7\u00e3o CP","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db"},"headline":"Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas","datePublished":"2023-12-05T18:08:02+00:00","dateModified":"2023-12-05T18:08:06+00:00","mainEntityOfPage":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/"},"wordCount":500,"commentCount":0,"publisher":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#primaryimage"},"thumbnailUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/12\/c877110731fa45e1b98314cb52a702b1.jpg","articleSection":["CIDADES","MANCHETE SEGUND\u00c1RIA","TODAS NOTICIAS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/","url":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/","name":"Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","isPartOf":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#primaryimage"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#primaryimage"},"thumbnailUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2023\/12\/c877110731fa45e1b98314cb52a702b1.jpg","datePublished":"2023-12-05T18:08:02+00:00","dateModified":"2023-12-05T18:08:06+00:00","breadcrumb":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/cleitonpinheiro.com.br\/site\/procon-faz-pesquisa-de-precos-das-mensalidades-das-escolas-particulares-de-palmas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cleitonpinheiro.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Procon faz pesquisa de pre\u00e7os das mensalidades das escolas particulares de Palmas"}]},{"@type":"WebSite","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#website","url":"https:\/\/cleitonpinheiro.com.br\/site\/","name":"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","description":"FALANDO A VERDADE","publisher":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cleitonpinheiro.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization","name":"CPNOT\u00cdCIAS","url":"https:\/\/cleitonpinheiro.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png","contentUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png","width":500,"height":500,"caption":"CPNOT\u00cdCIAS"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcpnoticias\/"]},{"@type":"Person","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db","name":"Reda\u00e7\u00e3o CP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g","caption":"Reda\u00e7\u00e3o CP"},"url":"https:\/\/cleitonpinheiro.com.br\/site\/author\/redacao\/"}]}},"views":164,"_links":{"self":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/75760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/comments?post=75760"}],"version-history":[{"count":1,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/75760\/revisions"}],"predecessor-version":[{"id":75762,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/75760\/revisions\/75762"}],"wp:attachment":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/media?parent=75760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/categories?post=75760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/tags?post=75760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}