{"id":76272,"date":"2024-01-13T08:17:35","date_gmt":"2024-01-13T11:17:35","guid":{"rendered":"https:\/\/cleitonpinheiro.com.br\/site\/?p=76272"},"modified":"2024-01-13T10:50:46","modified_gmt":"2024-01-13T13:50:46","slug":"projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas","status":"publish","type":"post","link":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/","title":{"rendered":"Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" src=\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/01\/1057811-ebc_07.12.2016-2948_07.12.16.webp\" alt=\"soja planta\u00e7\u00e3o mnocultura\" class=\"wp-image-76273\"\/><figcaption class=\"wp-element-caption\">Foto: Marcelo Camargo\/Ag\u00eancia Brasil<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">As condi\u00e7\u00f5es clim\u00e1ticas inst\u00e1veis do pa\u00eds levaram a Companhia Nacional de Abastecimento (Conab) a reduzir novamente a estimativa para a safra de gr\u00e3os de 2023\/24. A produ\u00e7\u00e3o brasileira deve chegar a 306,4 milh\u00f5es de toneladas, queda de 13,5 milh\u00f5es de toneladas em rela\u00e7\u00e3o \u00e0 safra passada (2022\/23), quando chegou a 319,9 milh\u00f5es de toneladas.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1576007&amp;o=node\"><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1576007&amp;o=node\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nesta quarta-feira (10), o \u00f3rg\u00e3o divulgou o quarto levantamento para o ciclo atual. \u201cAs condi\u00e7\u00f5es clim\u00e1ticas inst\u00e1veis, com chuvas escassas e mal distribu\u00eddas aliadas a altas temperaturas na regi\u00e3o central do pa\u00eds, al\u00e9m de precipita\u00e7\u00f5es volumosas na regi\u00e3o Sul, provocaram e ainda persistem no atraso do plantio da safra, al\u00e9m de influenciarem de maneira negativa no potencial produtivo das lavouras\u201d, explicou a Conab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com o \u00f3rg\u00e3o, esta safra vem tendo caracter\u00edsticas complexas para a estimativa de \u00e1rea, produtividade e produ\u00e7\u00e3o, j\u00e1 que os problemas clim\u00e1ticos geram incertezas e prejudicam a tomada de decis\u00e3o pelos produtores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Principal cultura cultivada no pa\u00eds, a soja deve apresentar uma produ\u00e7\u00e3o de 155,3 milh\u00f5es de toneladas. A estimativa \u00e9 menor do que a do \u00faltimo levantamento, de 160,2 milh\u00f5es de toneladas, mas ainda superior ao registrado na safra 2022\/23 (154,6 milh\u00f5es de toneladas). \u201cChuvas mal distribu\u00eddas e temperaturas elevadas influenciaram de maneira negativa tanto no plantio como no desenvolvimento das lavouras. As condi\u00e7\u00f5es clim\u00e1ticas tamb\u00e9m foram determinantes para alguns produtores migrarem para outras culturas, contribuindo para a redu\u00e7\u00e3o da \u00e1rea em rela\u00e7\u00e3o ao levantamento divulgado em dezembro\u201d, justificou a Conab.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No caso do milho, a produ\u00e7\u00e3o total est\u00e1 estimada em 117,6 milh\u00f5es de toneladas, redu\u00e7\u00e3o de 10,9% em rela\u00e7\u00e3o ao ciclo anterior. A queda \u00e9 reflexo de uma menor \u00e1rea plantada e de uma piora na expectativa de rendimento das lavouras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA primeira safra do cereal, que representa 20,7% da produ\u00e7\u00e3o, vem passando por situa\u00e7\u00f5es adversas como elevadas precipita\u00e7\u00f5es nos estados do Sul, baixas pluviosidades acompanhadas pelas altas temperaturas no Centro-Oeste\u201d, explicou a companhia. Para a segunda safra, al\u00e9m de avaliar os custos, as decis\u00f5es dos produtores dependem de fatores clim\u00e1ticos, de disponibilidade de janela para o plantio e dos pre\u00e7os de mercado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Arroz e feij\u00e3o<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 o arroz tem uma estimativa de produ\u00e7\u00e3o de 10,8 milh\u00f5es de toneladas, 7,2% a mais que a \u00faltima safra. Segundo o boletim, os pre\u00e7os do gr\u00e3o foram incentivos para o aumento de \u00e1rea em alguns estados produtores. Por outro lado, o atraso no plantio, o volume excessivo de chuvas ou de per\u00edodos de veranicos que ocorreram em regi\u00f5es diversas, al\u00e9m das dificuldades nos tratos culturais, s\u00e3o condi\u00e7\u00f5es desfavor\u00e1veis para a produtividade.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o feij\u00e3o, \u00e9 esperada uma estabilidade na produ\u00e7\u00e3o, quando se compara com a safra passada, chegando a uma colheita de 3,03 milh\u00f5es de toneladas. Entretanto, a Conab alerta que a primeira safra da leguminosa caminha para a conclus\u00e3o e vem apresentando altera\u00e7\u00f5es negativas, devido \u00e0 instabilidade do clima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 para o algod\u00e3o, \u00e9 esperado um crescimento de 6,2% na \u00e1rea cultivada. Com o plantio se aproximando a 32% no pa\u00eds, a \u00e1rea estimada em cerca de 1,77 milh\u00e3o de hectares poder\u00e1 variar, j\u00e1 que parte dela que deveria ser replantada com soja em Mato Grosso poder\u00e1 ser utilizada com o plantio da fibra. Atualmente a proje\u00e7\u00e3o \u00e9 de uma colheita de 3,1 milh\u00f5es de toneladas de pluma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com a colheita encerrada, o trigo registra uma produ\u00e7\u00e3o de 8,1 milh\u00f5es de toneladas. Segundo a Conab, at\u00e9 o in\u00edcio da fase reprodutiva, as condi\u00e7\u00f5es clim\u00e1ticas vinham beneficiando a cultura, com perspectivas de uma safra recorde semelhante \u00e0 de 2022. Mas, a partir de setembro, teve in\u00edcio um per\u00edodo com chuvas excessivas que persistiu at\u00e9 a colheita, situa\u00e7\u00e3o que causou perdas na produtividade.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Com\u00e9rcio<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Sobre o mercado das&nbsp;<em>commodities&nbsp;<\/em>brasileiras, a redu\u00e7\u00e3o na estimativa da produ\u00e7\u00e3o de soja dever\u00e1 implicar tamb\u00e9m uma menor exporta\u00e7\u00e3o da oleaginosa em gr\u00e3os neste ano. Al\u00e9m disso, o Conselho Nacional de Pol\u00edtica Energ\u00e9tica (CNPE) aprovou o aumento de biodiesel ao diesel, de 12% para 14% [https:\/\/agenciabrasil.ebc.com.br\/economia\/noticia\/2023-12\/percentual-de-biodiesel-no-diesel-subira-para-14-em-marco-de-2024], o que, para a companhia, indica que haver\u00e1 um incremento na demanda interna de \u00f3leo de soja.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o arroz, estima-se uma manuten\u00e7\u00e3o do consumo nacional em 10,3 milh\u00f5es de toneladas. \u201cA recupera\u00e7\u00e3o produtiva e a menor oferta de importantes pa\u00edses exportadores, possivelmente, resultar\u00e3o em um aumento para 2 milh\u00f5es de toneladas no volume exportado pelo Brasil. Projeta-se uma manuten\u00e7\u00e3o do volume importado em 1,5 milh\u00e3o, em raz\u00e3o ainda da necessidade de recomposi\u00e7\u00e3o da oferta nacional\u201d, explicou a Conab, lembrando que a estimativa \u00e9 de aumento da produ\u00e7\u00e3o do gr\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os estoques de arroz devem ficar pr\u00f3ximos da estabilidade, estimados em 1,7 milh\u00e3o de toneladas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">J\u00e1 a estimativa de menor produ\u00e7\u00e3o de milho para a safra 2023\/24, somada \u00e0 maior oferta dispon\u00edvel no mercado internacional (em meio \u00e0 boa safra norte-americana), dever\u00e1 reduzir o volume de exporta\u00e7\u00f5es brasileiras do gr\u00e3o em 2024. Ainda assim, o Brasil deve continuar a ser o maior exportador de milho do mundo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para o trigo, apesar do bom volume colhido, em raz\u00e3o dos problemas clim\u00e1ticos houve perda da qualidade e ser\u00e1 necess\u00e1rio importar mais trigo, passando de 6 milh\u00f5es para 6,2 milh\u00f5es de toneladas compradas do exterior. Com as altera\u00e7\u00f5es, a estimativa da Conab \u00e9 encerrar a safra 2023\/24 com estoque de passagem de 393,6 mil toneladas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No caso do algod\u00e3o, o boletim destaca que a melhora que vem ocorrendo no desempenho da economia nacional tende impulsionar o consumo interno da pluma em 2024, que deve ficar em torno de 730 mil toneladas. Como as exporta\u00e7\u00f5es apresentam um crescimento e devem atingir 2,5 milh\u00f5es de toneladas, o estoque final de algod\u00e3o dever\u00e1 cair para 2,04 milh\u00f5es de toneladas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os boletins das safras brasileiras est\u00e3o dispon\u00edveis no&nbsp;<a href=\"https:\/\/www.conab.gov.br\/info-agro\/safras\" target=\"_blank\" rel=\"noreferrer noopener\"><em>site<\/em>&nbsp;da Conab<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por Andreia Verd\u00e9lio \u2013 Rep\u00f3rter da Ag\u00eancia Brasil<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As condi\u00e7\u00f5es clim\u00e1ticas inst\u00e1veis do pa\u00eds levaram a Companhia Nacional de Abastecimento (Conab) a reduzir novamente a estimativa para a safra de gr\u00e3os de 2023\/24. A produ\u00e7\u00e3o brasileira deve chegar a 306,4 milh\u00f5es de toneladas, queda de 13,5 milh\u00f5es de toneladas em rela\u00e7\u00e3o \u00e0 safra passada (2022\/23), quando chegou a 319,9 milh\u00f5es de toneladas. Nesta [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[19,898,21],"tags":[],"class_list":["post-76272","post","type-post","status-publish","format-standard","hentry","category-brasil-mundo","category-manchete-segundaria","category-todas-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\" \/>\n<meta property=\"og:description\" content=\"As condi\u00e7\u00f5es clim\u00e1ticas inst\u00e1veis do pa\u00eds levaram a Companhia Nacional de Abastecimento (Conab) a reduzir novamente a estimativa para a safra de gr\u00e3os de 2023\/24. A produ\u00e7\u00e3o brasileira deve chegar a 306,4 milh\u00f5es de toneladas, queda de 13,5 milh\u00f5es de toneladas em rela\u00e7\u00e3o \u00e0 safra passada (2022\/23), quando chegou a 319,9 milh\u00f5es de toneladas. Nesta [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/\" \/>\n<meta property=\"og:site_name\" content=\"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcpnoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-13T11:17:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-13T13:50:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/01\/1057811-ebc_07.12.2016-2948_07.12.16.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o CP\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o CP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o CP\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db\"},\"headline\":\"Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas\",\"datePublished\":\"2024-01-13T11:17:35+00:00\",\"dateModified\":\"2024-01-13T13:50:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/\"},\"wordCount\":1041,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/01\/1057811-ebc_07.12.2016-2948_07.12.16.webp\",\"articleSection\":[\"BRASIL \/ MUNDO\",\"MANCHETE SEGUND\u00c1RIA\",\"TODAS NOTICIAS\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/\",\"name\":\"Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\",\"isPartOf\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/01\/1057811-ebc_07.12.2016-2948_07.12.16.webp\",\"datePublished\":\"2024-01-13T11:17:35+00:00\",\"dateModified\":\"2024-01-13T13:50:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/cleitonpinheiro.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#website\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/\",\"name\":\"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\",\"description\":\"FALANDO A VERDADE\",\"publisher\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cleitonpinheiro.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\",\"name\":\"CPNOT\u00cdCIAS\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png\",\"contentUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png\",\"width\":500,\"height\":500,\"caption\":\"CPNOT\u00cdCIAS\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/portalcpnoticias\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db\",\"name\":\"Reda\u00e7\u00e3o CP\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g\",\"caption\":\"Reda\u00e7\u00e3o CP\"},\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/author\/redacao\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/","og_locale":"pt_BR","og_type":"article","og_title":"Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","og_description":"As condi\u00e7\u00f5es clim\u00e1ticas inst\u00e1veis do pa\u00eds levaram a Companhia Nacional de Abastecimento (Conab) a reduzir novamente a estimativa para a safra de gr\u00e3os de 2023\/24. A produ\u00e7\u00e3o brasileira deve chegar a 306,4 milh\u00f5es de toneladas, queda de 13,5 milh\u00f5es de toneladas em rela\u00e7\u00e3o \u00e0 safra passada (2022\/23), quando chegou a 319,9 milh\u00f5es de toneladas. Nesta [&hellip;]","og_url":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/","og_site_name":"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","article_publisher":"https:\/\/www.facebook.com\/portalcpnoticias\/","article_published_time":"2024-01-13T11:17:35+00:00","article_modified_time":"2024-01-13T13:50:46+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/01\/1057811-ebc_07.12.2016-2948_07.12.16.webp","type":"image\/webp"}],"author":"Reda\u00e7\u00e3o CP","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o CP","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#article","isPartOf":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/"},"author":{"name":"Reda\u00e7\u00e3o CP","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db"},"headline":"Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas","datePublished":"2024-01-13T11:17:35+00:00","dateModified":"2024-01-13T13:50:46+00:00","mainEntityOfPage":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/"},"wordCount":1041,"commentCount":0,"publisher":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#primaryimage"},"thumbnailUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/01\/1057811-ebc_07.12.2016-2948_07.12.16.webp","articleSection":["BRASIL \/ MUNDO","MANCHETE SEGUND\u00c1RIA","TODAS NOTICIAS"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/","url":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/","name":"Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","isPartOf":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#primaryimage"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#primaryimage"},"thumbnailUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/01\/1057811-ebc_07.12.2016-2948_07.12.16.webp","datePublished":"2024-01-13T11:17:35+00:00","dateModified":"2024-01-13T13:50:46+00:00","breadcrumb":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/cleitonpinheiro.com.br\/site\/projecao-da-safra-de-graos-2023-24-cai-para-3064-milhoes-de-toneladas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cleitonpinheiro.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Proje\u00e7\u00e3o da safra de gr\u00e3os 2023\/24 cai para 306,4 milh\u00f5es de toneladas"}]},{"@type":"WebSite","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#website","url":"https:\/\/cleitonpinheiro.com.br\/site\/","name":"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","description":"FALANDO A VERDADE","publisher":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cleitonpinheiro.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization","name":"CPNOT\u00cdCIAS","url":"https:\/\/cleitonpinheiro.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png","contentUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png","width":500,"height":500,"caption":"CPNOT\u00cdCIAS"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcpnoticias\/"]},{"@type":"Person","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/8f04544e0bc40a1b68775b08360f87db","name":"Reda\u00e7\u00e3o CP","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0bcf19cb29fdc8fc588c490c7ae1b3e174dac268586a63fbe1d1893a0f9020cd?s=96&r=g","caption":"Reda\u00e7\u00e3o CP"},"url":"https:\/\/cleitonpinheiro.com.br\/site\/author\/redacao\/"}]}},"views":92,"_links":{"self":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/76272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/comments?post=76272"}],"version-history":[{"count":2,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/76272\/revisions"}],"predecessor-version":[{"id":76278,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/76272\/revisions\/76278"}],"wp:attachment":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/media?parent=76272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/categories?post=76272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/tags?post=76272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}