{"id":83025,"date":"2024-11-22T16:47:58","date_gmt":"2024-11-22T19:47:58","guid":{"rendered":"https:\/\/cleitonpinheiro.com.br\/site\/?p=83025"},"modified":"2024-11-22T16:48:02","modified_gmt":"2024-11-22T19:48:02","slug":"tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte","status":"publish","type":"post","link":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/","title":{"rendered":"Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte"},"content":{"rendered":"\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" data-id=\"83026\" src=\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/11\/CAPA-MATERIA-1024x576.png\" alt=\"\" class=\"wp-image-83026\"\/><figcaption class=\"wp-element-caption\">Foto: Divulga\u00e7\u00e3o <\/figcaption><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">O Estado do Tocantins registrou a segunda menor taxa de desemprego da regi\u00e3o Norte no terceiro trimestre deste ano, com 5% de desocupa\u00e7\u00e3o em um universo de 1,3 milh\u00e3o de pessoas em idade de trabalhar, atr\u00e1s apenas do Estado de Rond\u00f4nia, que apresentou uma taxa de 2,1%. O desemprego no Tocantins tamb\u00e9m ficou abaixo da m\u00e9dia nacional, que foi de 6,4%. Os n\u00fameros foram divulgados nesta sexta-feira, 22, pela Pesquisa Nacional por Amostra de Domic\u00edlios (PNAD Cont\u00ednua).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Foi a menor taxa de desemprego registrada em um terceiro trimestre nos \u00faltimos tr\u00eas anos. Na compara\u00e7\u00e3o com o terceiro trimestre de 2021, quando o Tocantins registrava 10,8% de desocupa\u00e7\u00e3o, a queda na taxa de desemprego foi de 5,8 pontos percentuais (p.p.).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cAtribu\u00edmos essa queda expressiva de desemprego ao forte investimento que a gest\u00e3o do Governador Wanderlei Barbosa vem fazendo para diversificar e fomentar nossa economia, estimulando todos os setores, desde a agricultura familiar e pequenas cooperativas at\u00e9 a melhoria do ambiente de neg\u00f3cios para grandes investidores e players dos cen\u00e1rios nacional e internacional\u201d, explicou o secret\u00e1rio de Estado da Ind\u00fastria, Com\u00e9rcio e Servi\u00e7os, Carlos Humberto Lima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ainda na pesquisa, o Tocantins aparece como a unidade da Federa\u00e7\u00e3o com a menor taxa de pessoas trabalhando por conta pr\u00f3pria \u2014 s\u00e3o 19,9% de trabalhadores nessa condi\u00e7\u00e3o, ante a m\u00e9dia nacional de 24,6%. O estado com o maior n\u00famero de pessoas trabalhando por conta pr\u00f3pria foi Rond\u00f4nia (33,6%).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Estratifica\u00e7\u00e3o<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A metodologia da PNAD Cont\u00ednua considera \u201cpessoas em idade de trabalhar\u201d a popula\u00e7\u00e3o com 14 anos ou mais, na data da pesquisa, que no Tocantins contabiliza 1,305 milh\u00e3o de pessoas. Desse montante, de acordo com a pesquisa, 834 mil j\u00e1 fazem parte da for\u00e7a de trabalho dispon\u00edvel; outras 472 mil pessoas ainda n\u00e3o ingressaram no mercado, apesar de estarem aptas ao trabalho.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A maior parte dos trabalhadores (340 mil) est\u00e1 empregada no setor privado, sendo 187 mil com carteira assinada. O setor p\u00fablico emprega a segunda maior fatia de trabalhadores no Tocantins, com 198 mil. Outras 158 mil pessoas trabalham por conta pr\u00f3pria e h\u00e1 ainda 48 mil trabalhadores dom\u00e9sticos empregados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O grupo de atividades que inclui administra\u00e7\u00e3o p\u00fablica, defesa, seguridade social, educa\u00e7\u00e3o, sa\u00fade humana e servi\u00e7os sociais \u00e9 o que mais emprega, com 225 mil trabalhadores. Em seguida, aparece o grupo de com\u00e9rcio, repara\u00e7\u00e3o de ve\u00edculos automotores e motocicletas, com 139 mil empregados. As atividades de agricultura, pecu\u00e1ria, produ\u00e7\u00e3o florestal, pesca e aquicultura aparecem em terceiro lugar, empregando 97 mil trabalhadores tocantinenses.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Renda<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com os dados obtidos pelo IBGE, o rendimento m\u00e9dio real mensal do tocantinense foi de R$ 2.753, mantendo-se est\u00e1vel em rela\u00e7\u00e3o aos semestres anteriores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Texto: Adenauer Cunha\/Governo do Tocantins<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Estado do Tocantins registrou a segunda menor taxa de desemprego da regi\u00e3o Norte no terceiro trimestre deste ano, com 5% de desocupa\u00e7\u00e3o em um universo de 1,3 milh\u00e3o de pessoas em idade de trabalhar, atr\u00e1s apenas do Estado de Rond\u00f4nia, que apresentou uma taxa de 2,1%. O desemprego no Tocantins tamb\u00e9m ficou abaixo da [&hellip;]<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,898],"tags":[72],"class_list":["post-83025","post","type-post","status-publish","format-standard","hentry","category-estado","category-manchete-segundaria","tag-tocantins"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\" \/>\n<meta property=\"og:description\" content=\"O Estado do Tocantins registrou a segunda menor taxa de desemprego da regi\u00e3o Norte no terceiro trimestre deste ano, com 5% de desocupa\u00e7\u00e3o em um universo de 1,3 milh\u00e3o de pessoas em idade de trabalhar, atr\u00e1s apenas do Estado de Rond\u00f4nia, que apresentou uma taxa de 2,1%. O desemprego no Tocantins tamb\u00e9m ficou abaixo da [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/\" \/>\n<meta property=\"og:site_name\" content=\"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/portalcpnoticias\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-22T19:47:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-22T19:48:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/11\/CAPA-MATERIA.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maria Inez Freitas de Oliveira\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Inez Freitas de Oliveira\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/\"},\"author\":{\"name\":\"Maria Inez Freitas de Oliveira\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/afd66d2092a2af96277ec94d0fdca5e9\"},\"headline\":\"Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte\",\"datePublished\":\"2024-11-22T19:47:58+00:00\",\"dateModified\":\"2024-11-22T19:48:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/\"},\"wordCount\":482,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/11\/CAPA-MATERIA-1024x576.png\",\"keywords\":[\"tocantins\"],\"articleSection\":[\"ESTADO\",\"MANCHETE SEGUND\u00c1RIA\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/\",\"name\":\"Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\",\"isPartOf\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/11\/CAPA-MATERIA-1024x576.png\",\"datePublished\":\"2024-11-22T19:47:58+00:00\",\"dateModified\":\"2024-11-22T19:48:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/cleitonpinheiro.com.br\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#website\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/\",\"name\":\"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO\",\"description\":\"FALANDO A VERDADE\",\"publisher\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/cleitonpinheiro.com.br\/site\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#organization\",\"name\":\"CPNOT\u00cdCIAS\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png\",\"contentUrl\":\"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png\",\"width\":500,\"height\":500,\"caption\":\"CPNOT\u00cdCIAS\"},\"image\":{\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/portalcpnoticias\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/afd66d2092a2af96277ec94d0fdca5e9\",\"name\":\"Maria Inez Freitas de Oliveira\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8da4748da444fee870fe4880de74d9dd08b34df8aabd6158765ed760cf8cd7c8?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8da4748da444fee870fe4880de74d9dd08b34df8aabd6158765ed760cf8cd7c8?s=96&r=g\",\"caption\":\"Maria Inez Freitas de Oliveira\"},\"url\":\"https:\/\/cleitonpinheiro.com.br\/site\/author\/inez\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/","og_locale":"pt_BR","og_type":"article","og_title":"Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","og_description":"O Estado do Tocantins registrou a segunda menor taxa de desemprego da regi\u00e3o Norte no terceiro trimestre deste ano, com 5% de desocupa\u00e7\u00e3o em um universo de 1,3 milh\u00e3o de pessoas em idade de trabalhar, atr\u00e1s apenas do Estado de Rond\u00f4nia, que apresentou uma taxa de 2,1%. O desemprego no Tocantins tamb\u00e9m ficou abaixo da [&hellip;]","og_url":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/","og_site_name":"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","article_publisher":"https:\/\/www.facebook.com\/portalcpnoticias\/","article_published_time":"2024-11-22T19:47:58+00:00","article_modified_time":"2024-11-22T19:48:02+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/11\/CAPA-MATERIA.png","type":"image\/png"}],"author":"Maria Inez Freitas de Oliveira","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Maria Inez Freitas de Oliveira","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#article","isPartOf":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/"},"author":{"name":"Maria Inez Freitas de Oliveira","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/afd66d2092a2af96277ec94d0fdca5e9"},"headline":"Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte","datePublished":"2024-11-22T19:47:58+00:00","dateModified":"2024-11-22T19:48:02+00:00","mainEntityOfPage":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/"},"wordCount":482,"commentCount":0,"publisher":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/11\/CAPA-MATERIA-1024x576.png","keywords":["tocantins"],"articleSection":["ESTADO","MANCHETE SEGUND\u00c1RIA"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/","url":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/","name":"Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte - PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","isPartOf":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#primaryimage"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#primaryimage"},"thumbnailUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2024\/11\/CAPA-MATERIA-1024x576.png","datePublished":"2024-11-22T19:47:58+00:00","dateModified":"2024-11-22T19:48:02+00:00","breadcrumb":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/cleitonpinheiro.com.br\/site\/tocantins-tem-a-segunda-menor-taxa-de-desemprego-da-regiao-norte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cleitonpinheiro.com.br\/site\/"},{"@type":"ListItem","position":2,"name":"Tocantins tem a segunda menor taxa de desemprego da regi\u00e3o Norte"}]},{"@type":"WebSite","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#website","url":"https:\/\/cleitonpinheiro.com.br\/site\/","name":"PORTAL DE NOT\u00cdCIAS CLEITON PINHEIRO","description":"FALANDO A VERDADE","publisher":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cleitonpinheiro.com.br\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#organization","name":"CPNOT\u00cdCIAS","url":"https:\/\/cleitonpinheiro.com.br\/site\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/","url":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png","contentUrl":"https:\/\/cleitonpinheiro.com.br\/site\/wp-content\/uploads\/2022\/08\/Logo-pequena-2.png","width":500,"height":500,"caption":"CPNOT\u00cdCIAS"},"image":{"@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/portalcpnoticias\/"]},{"@type":"Person","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/afd66d2092a2af96277ec94d0fdca5e9","name":"Maria Inez Freitas de Oliveira","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cleitonpinheiro.com.br\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8da4748da444fee870fe4880de74d9dd08b34df8aabd6158765ed760cf8cd7c8?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8da4748da444fee870fe4880de74d9dd08b34df8aabd6158765ed760cf8cd7c8?s=96&r=g","caption":"Maria Inez Freitas de Oliveira"},"url":"https:\/\/cleitonpinheiro.com.br\/site\/author\/inez\/"}]}},"views":239,"_links":{"self":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/83025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/comments?post=83025"}],"version-history":[{"count":1,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/83025\/revisions"}],"predecessor-version":[{"id":83027,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/posts\/83025\/revisions\/83027"}],"wp:attachment":[{"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/media?parent=83025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/categories?post=83025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cleitonpinheiro.com.br\/site\/wp-json\/wp\/v2\/tags?post=83025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}